{"id":2751,"count":1,"description":"","link":"https:\/\/perfectyourenglish.com\/blog\/tag\/class-4-kind-of-sentence-worksheet\/","name":"class 4 kind of sentence worksheet","slug":"class-4-kind-of-sentence-worksheet","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/tags\/2751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/posts?tags=2751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}