{"id":3496,"count":2,"description":"","link":"https:\/\/perfectyourenglish.com\/blog\/tag\/phrases-worksheet-for-class-8\/","name":"phrases worksheet for class 8","slug":"phrases-worksheet-for-class-8","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/tags\/3496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/perfectyourenglish.com\/blog\/wp-json\/wp\/v2\/posts?tags=3496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}